{"id":648,"count":1,"description":"","link":"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/","name":"pregnancy during festive season","slug":"pregnancy-during-festive-season","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>pregnancy during festive season Archives - Stem Cell Banking Guide and Pregnancy Tips For New Parents<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pregnancy during festive season Archives - Stem Cell Banking Guide and Pregnancy Tips For New Parents\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/\" \/>\n<meta property=\"og:site_name\" content=\"Stem Cell Banking Guide and Pregnancy Tips For New Parents\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/\",\"url\":\"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/\",\"name\":\"pregnancy during festive season Archives - Stem Cell Banking Guide and Pregnancy Tips For New Parents\",\"isPartOf\":{\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cordlifeindia.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pregnancy during festive season\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/#website\",\"url\":\"https:\/\/www.cordlifeindia.com\/blog\/\",\"name\":\"Stem Cell Banking Guide and Pregnancy Tips For New Parents\",\"description\":\"Cordlife India\",\"publisher\":{\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cordlifeindia.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/#organization\",\"name\":\"Cordlife Sciences India Pvt Ltd\",\"url\":\"https:\/\/www.cordlifeindia.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cordlifeindia.com\/blog\/wp-content\/uploads\/2019\/04\/CordLife_Logo_201505.png\",\"contentUrl\":\"https:\/\/www.cordlifeindia.com\/blog\/wp-content\/uploads\/2019\/04\/CordLife_Logo_201505.png\",\"width\":618,\"height\":270,\"caption\":\"Cordlife Sciences India Pvt Ltd\"},\"image\":{\"@id\":\"https:\/\/www.cordlifeindia.com\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pregnancy during festive season Archives - Stem Cell Banking Guide and Pregnancy Tips For New Parents","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/","og_locale":"en_GB","og_type":"article","og_title":"pregnancy during festive season Archives - Stem Cell Banking Guide and Pregnancy Tips For New Parents","og_url":"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/","og_site_name":"Stem Cell Banking Guide and Pregnancy Tips For New Parents","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/","url":"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/","name":"pregnancy during festive season Archives - Stem Cell Banking Guide and Pregnancy Tips For New Parents","isPartOf":{"@id":"https:\/\/www.cordlifeindia.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cordlifeindia.com\/blog\/tag\/pregnancy-during-festive-season\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cordlifeindia.com\/blog\/"},{"@type":"ListItem","position":2,"name":"pregnancy during festive season"}]},{"@type":"WebSite","@id":"https:\/\/www.cordlifeindia.com\/blog\/#website","url":"https:\/\/www.cordlifeindia.com\/blog\/","name":"Stem Cell Banking Guide and Pregnancy Tips For New Parents","description":"Cordlife India","publisher":{"@id":"https:\/\/www.cordlifeindia.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cordlifeindia.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.cordlifeindia.com\/blog\/#organization","name":"Cordlife Sciences India Pvt Ltd","url":"https:\/\/www.cordlifeindia.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cordlifeindia.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.cordlifeindia.com\/blog\/wp-content\/uploads\/2019\/04\/CordLife_Logo_201505.png","contentUrl":"https:\/\/www.cordlifeindia.com\/blog\/wp-content\/uploads\/2019\/04\/CordLife_Logo_201505.png","width":618,"height":270,"caption":"Cordlife Sciences India Pvt Ltd"},"image":{"@id":"https:\/\/www.cordlifeindia.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cordlifeindia.com\/blog\/wp-json\/wp\/v2\/tags\/648"}],"collection":[{"href":"https:\/\/www.cordlifeindia.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.cordlifeindia.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.cordlifeindia.com\/blog\/wp-json\/wp\/v2\/posts?tags=648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}